{"id":10781,"date":"2025-01-10T08:48:48","date_gmt":"2025-01-10T05:48:48","guid":{"rendered":"https:\/\/www.alapalaacademy.com\/bas-degirmenci-kursu-tamamlandi\/"},"modified":"2025-01-21T16:46:17","modified_gmt":"2025-01-21T13:46:17","slug":"bas-degirmenci-kursu-tamamlandi","status":"publish","type":"post","link":"https:\/\/www.alapalaacademy.com\/tr\/bas-degirmenci-kursu-tamamlandi\/","title":{"rendered":"Ba\u015f De\u011firmenci Kursu Tamamland\u0131"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10781\" class=\"elementor elementor-10781 elementor-10763\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-673594f elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"673594f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d0e902\" data-id=\"1d0e902\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea37a03 elementor-widget elementor-widget-text-editor\" data-id=\"ea37a03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<blockquote>\n<p>Tah\u0131ldan M\u00fckemmelli\u011fe: Ba\u015f De\u011firmenci Sertifikas\u0131.<\/p>\n<\/blockquote>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63c1c74 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"63c1c74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b9c541\" data-id=\"6b9c541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1b4586 elementor-widget elementor-widget-text-editor\" data-id=\"c1b4586\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alapala Akademi&#8217;deki Ba\u015f De\u011firmenci E\u011fitim Program\u0131 18-29 Kas\u0131m 2024 tarihleri aras\u0131nda ba\u015far\u0131yla ger\u00e7ekle\u015ftirildi. Kat\u0131l\u0131mc\u0131lar, temizleme, tavlama, \u00f6\u011f\u00fctme ve paketleme dahil olmak \u00fczere de\u011firmencilik s\u00fcrecinin t\u00fcm y\u00f6nlerini kapsayan kapsaml\u0131 teorik ve pratik oturumlara kat\u0131ld\u0131lar. Programda ayr\u0131ca Alapala&#8217;n\u0131n son teknoloji \u00fcr\u00fcn\u00fc test de\u011firmeninde uygulamal\u0131 e\u011fitim verilerek kat\u0131l\u0131mc\u0131lara modern \u00f6\u011f\u00fctme teknolojileri konusunda de\u011ferli deneyimler kazand\u0131r\u0131ld\u0131. E\u011fitimin tamamlanmas\u0131n\u0131n ard\u0131ndan kat\u0131l\u0131mc\u0131lara, de\u011firmencilik sekt\u00f6r\u00fcndeki uzmanl\u0131klar\u0131n\u0131 ve m\u00fckemmeliyete olan ba\u011fl\u0131l\u0131klar\u0131n\u0131 g\u00f6steren sertifikalar verildi.   <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be16b66 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"be16b66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd8a8e9\" data-id=\"cd8a8e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6197d2f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6197d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC02199.webp\" alt=\"Alapala-Academy-2025-DSC02199\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC02042.webp\" alt=\"Alapala-Academy-2025-DSC02042\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC02032.webp\" alt=\"Alapala-Academy-2025-DSC02032\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01957.webp\" alt=\"Alapala-Academy-2025-DSC01957\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01907.webp\" alt=\"Alapala-Academy-2025-DSC01907\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01853.webp\" alt=\"Alapala-Academy-2025-DSC01853\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01842.webp\" alt=\"Alapala-Academy-2025-DSC01842\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01822.webp\" alt=\"Alapala-Academy-2025-DSC01822\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01806.webp\" alt=\"Alapala-Academy-2025-DSC01806\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01751.webp\" alt=\"Alapala-Academy-2025-DSC01751\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01728.webp\" alt=\"Alapala-Academy-2025-DSC01728\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01721.webp\" alt=\"Alapala-Academy-2025-DSC01721\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01668.webp\" alt=\"Alapala-Academy-2025-DSC01668\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01655.webp\" alt=\"Alapala-Academy-2025-DSC01655\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01634.webp\" alt=\"Alapala-Academy-2025-DSC01634\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01607.webp\" alt=\"Alapala-Academy-2025-DSC01607\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01592.webp\" alt=\"Alapala-Academy-2025-DSC01592\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01540.webp\" alt=\"Alapala-Academy-2025-DSC01540\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01525.webp\" alt=\"Alapala-Academy-2025-DSC01525\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01474.webp\" alt=\"Alapala-Academy-2025-DSC01474\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01457.webp\" alt=\"Alapala-Academy-2025-DSC01457\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01262.webp\" alt=\"Alapala-Academy-2025-DSC01262\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01239.webp\" alt=\"Alapala-Academy-2025-DSC01239\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 \/ 24\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.alapalaacademy.com\/wp-content\/uploads\/2025\/01\/Alapala-Academy-2025-DSC01237.webp\" alt=\"Alapala-Academy-2025-DSC01237\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a58b3f elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"8a58b3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdfd3ba\" data-id=\"cdfd3ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9453c7a elementor-widget elementor-widget-video\" data-id=\"9453c7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/4lD5YdUpq1Y?si=Gb4lT9I5kUdX3C-r&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tah\u0131ldan M\u00fckemmelli\u011fe: Ba\u015f De\u011firmenci Sertifikas\u0131. Alapala Akademi&#8217;deki Ba\u015f De\u011firmenci E\u011fitim Program\u0131 18-29 Kas\u0131m 2024 tarihleri aras\u0131nda ba\u015far\u0131yla ger\u00e7ekle\u015ftirildi. Kat\u0131l\u0131mc\u0131lar, temizleme, tavlama, \u00f6\u011f\u00fctme ve paketleme dahil olmak \u00fczere de\u011firmencilik s\u00fcrecinin t\u00fcm y\u00f6nlerini kapsayan kapsaml\u0131 teorik ve pratik oturumlara kat\u0131ld\u0131lar. Programda ayr\u0131ca Alapala&#8217;n\u0131n son teknoloji \u00fcr\u00fcn\u00fc test de\u011firmeninde uygulamal\u0131 e\u011fitim verilerek kat\u0131l\u0131mc\u0131lara modern \u00f6\u011f\u00fctme teknolojileri konusunda de\u011ferli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80,79],"tags":[],"class_list":["post-10781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-haberler","category-kurslar"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/posts\/10781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/comments?post=10781"}],"version-history":[{"count":0,"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/posts\/10781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/media\/10746"}],"wp:attachment":[{"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/media?parent=10781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/categories?post=10781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alapalaacademy.com\/tr\/wp-json\/wp\/v2\/tags?post=10781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}